{"id":1088,"date":"2025-10-28T10:01:10","date_gmt":"2025-10-28T14:01:10","guid":{"rendered":"https:\/\/havenhousetn.org\/?post_type=tribe_events&#038;p=1088"},"modified":"2025-10-28T10:01:38","modified_gmt":"2025-10-28T14:01:38","slug":"%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8","status":"publish","type":"tribe_events","link":"https:\/\/havenhousetn.org\/es\/event\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\/","title":{"rendered":"Hope for the Holidays!"},"content":{"rendered":"<p data-start=\"34\" data-end=\"255\">Join us on <strong data-start=\"45\" data-end=\"63\">Monday, Nov. 4<\/strong> at <strong data-start=\"67\" data-end=\"84\">J. Danforth\u2019s<\/strong> for a special <strong data-start=\"99\" data-end=\"122\">Haven House Benefit<\/strong> \u2014 an exclusive evening to <strong data-start=\"149\" data-end=\"181\">shop early before the public<\/strong> and support women and families right here in the <strong data-start=\"231\" data-end=\"250\">Maryville area.<\/strong> \ud83d\udc9b<\/p>\n<p data-start=\"257\" data-end=\"399\">\ud83c\udf9f\ufe0f <strong data-start=\"261\" data-end=\"289\">Tickets are on sale now!<\/strong> Grab yours and be part of this meaningful kickoff to the holiday season. \ud83d\udecd\ufe0f\ud83d\udc9c<\/p>","protected":false},"excerpt":{"rendered":"<p>Join us on Monday, Nov. 4 at J. Danforth\u2019s for a special Haven House Benefit \u2014 an exclusive evening to shop early before the public and support women and families right here in the Maryville area. \ud83d\udc9b \ud83c\udf9f\ufe0f Tickets are on sale now! Grab yours and be part of this meaningful kickoff to the holiday [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1088","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hope for the Holidays! - Haven House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/havenhousetn.org\/es\/event\/\u2728-hope-for-the-holidays-\u2728\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hope for the Holidays! - Haven House\" \/>\n<meta property=\"og:description\" content=\"Join us on Monday, Nov. 4 at J. Danforth\u2019s for a special Haven House Benefit \u2014 an exclusive evening to shop early before the public and support women and families right here in the Maryville area. \ud83d\udc9b \ud83c\udf9f\ufe0f Tickets are on sale now! Grab yours and be part of this meaningful kickoff to the holiday [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/havenhousetn.org\/es\/event\/\u2728-hope-for-the-holidays-\u2728\/\" \/>\n<meta property=\"og:site_name\" content=\"Haven House\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T14:01:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/event\\\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\\\/\",\"url\":\"https:\\\/\\\/havenhousetn.org\\\/event\\\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\\\/\",\"name\":\"Hope for the Holidays! - Haven House\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/#website\"},\"datePublished\":\"2025-10-28T14:01:10+00:00\",\"dateModified\":\"2025-10-28T14:01:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/event\\\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/havenhousetn.org\\\/event\\\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/event\\\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/havenhousetn.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/havenhousetn.org\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hope for the Holidays!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/#website\",\"url\":\"https:\\\/\\\/havenhousetn.org\\\/\",\"name\":\"Haven House\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/havenhousetn.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/#organization\",\"name\":\"Haven House\",\"url\":\"https:\\\/\\\/havenhousetn.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/havenhousetn.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/HH-Logo-White-2@2x.png\",\"contentUrl\":\"https:\\\/\\\/havenhousetn.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/HH-Logo-White-2@2x.png\",\"width\":686,\"height\":584,\"caption\":\"Haven House\"},\"image\":{\"@id\":\"https:\\\/\\\/havenhousetn.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hope for the Holidays! - Haven House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/havenhousetn.org\/es\/event\/\u2728-hope-for-the-holidays-\u2728\/","og_locale":"es_MX","og_type":"article","og_title":"Hope for the Holidays! - Haven House","og_description":"Join us on Monday, Nov. 4 at J. Danforth\u2019s for a special Haven House Benefit \u2014 an exclusive evening to shop early before the public and support women and families right here in the Maryville area. \ud83d\udc9b \ud83c\udf9f\ufe0f Tickets are on sale now! Grab yours and be part of this meaningful kickoff to the holiday [&hellip;]","og_url":"https:\/\/havenhousetn.org\/es\/event\/\u2728-hope-for-the-holidays-\u2728\/","og_site_name":"Haven House","article_modified_time":"2025-10-28T14:01:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/havenhousetn.org\/event\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\/","url":"https:\/\/havenhousetn.org\/event\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\/","name":"Hope for the Holidays! - Haven House","isPartOf":{"@id":"https:\/\/havenhousetn.org\/#website"},"datePublished":"2025-10-28T14:01:10+00:00","dateModified":"2025-10-28T14:01:38+00:00","breadcrumb":{"@id":"https:\/\/havenhousetn.org\/event\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/havenhousetn.org\/event\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/havenhousetn.org\/event\/%e2%9c%a8-hope-for-the-holidays-%e2%9c%a8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/havenhousetn.org\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/havenhousetn.org\/events\/"},{"@type":"ListItem","position":3,"name":"Hope for the Holidays!"}]},{"@type":"WebSite","@id":"https:\/\/havenhousetn.org\/#website","url":"https:\/\/havenhousetn.org\/","name":"Casa refugio","description":"","publisher":{"@id":"https:\/\/havenhousetn.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/havenhousetn.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/havenhousetn.org\/#organization","name":"Casa refugio","url":"https:\/\/havenhousetn.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/havenhousetn.org\/#\/schema\/logo\/image\/","url":"https:\/\/havenhousetn.org\/wp-content\/uploads\/2020\/11\/HH-Logo-White-2@2x.png","contentUrl":"https:\/\/havenhousetn.org\/wp-content\/uploads\/2020\/11\/HH-Logo-White-2@2x.png","width":686,"height":584,"caption":"Haven House"},"image":{"@id":"https:\/\/havenhousetn.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/tribe_events\/1088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/users\/13"}],"version-history":[{"count":0,"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/tribe_events\/1088\/revisions"}],"wp:attachment":[{"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/media?parent=1088"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/tags?post=1088"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/havenhousetn.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=1088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}